{"id":621,"date":"2019-04-28T13:34:14","date_gmt":"2019-04-28T13:34:14","guid":{"rendered":"https:\/\/nova-physiotherapie.de\/?p=621"},"modified":"2024-12-08T18:36:52","modified_gmt":"2024-12-08T18:36:52","slug":"welches-element-gehoert-zu-meinem-pferd-holz","status":"publish","type":"post","link":"https:\/\/nova-physiotherapie.de\/index.php\/2019\/04\/28\/welches-element-gehoert-zu-meinem-pferd-holz\/","title":{"rendered":"Welches Element geh\u00f6rt zu meinem Pferd? (Holz)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-1024x1024.png\" alt=\"\" class=\"wp-image-2123\" srcset=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-1024x1024.png 1024w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-300x300.png 300w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-150x150.png 150w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-768x768.png 768w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-1000x1000.png 1000w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-230x230.png 230w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-350x350.png 350w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz-480x480.png 480w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/006-Holz.png 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>In der traditionellen chinesischen Medizin, kurz TCM k\u00f6nnen\nPferde in f\u00fcnf unterschiedliche Typen eingeteilt werden. \n<\/p>\n\n\n\n<p>Diese entsprechen einem jeweiligen Organ und dessen Leitbahnen,\nsowie einem zugeh\u00f6rigen Element. Jeder Typ weist unterschiedliche\nk\u00f6rperliche und charakterliche Eigenschaften auf.<\/p>\n\n\n\n<p>Im Sinne der traditionellen chinesischen Medizin flie\u00dfen\nverschiedene Energieleitbahnen (Meridiane) durch den K\u00f6rper. Ist\nihre Energie nicht im Einklang oder wird durch andere Faktoren\ngest\u00f6rt treten verschiedene Krankheitssymptome auf.<\/p>\n\n\n\n<p><strong>Die Hauptmeridiane:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lunge \u2013 Dickdarm; Metall: Atemwegsprobleme -&gt; Lungen-Typ <\/li>\n\n\n\n<li>Magen \u2013 Milz; Erde : Gastro-Intestinalest\u00f6rungen -&gt; Milz-Typ <\/li>\n\n\n\n<li>Herz \u2013 D\u00fcnndarm; Feuer : Panikanf\u00e4lle, Kopfloswerden -&gt; Herz-Typ <\/li>\n\n\n\n<li>Blase \u2013 Niere; Wasser : R\u00fcckenbeschwerden -&gt; Nieren- Typ <\/li>\n\n\n\n<li>Perikard \u2013 3Erw\u00e4rmer; Feuer : Hypersensibilit\u00e4t  <\/li>\n\n\n\n<li>Gallenblase \u2013 Leber; Holz : Augenprobleme -&gt; Leber-Typ     <\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-6c531013 wp-block-group-is-layout-flex\">\n<p>In diesem Teil geht es um den Typen des Elements Holz. \n<\/p>\n<\/div>\n\n\n\n<p>Zum Holz z\u00e4hlen der Gallenblasen und der Leber-Meridian. Zugeh\u00f6rig sind die Augen und die Sehnen. (Sehen und Sehnen)<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-1024x683.jpg\" alt=\"\" class=\"wp-image-645 size-full\" srcset=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-1024x683.jpg 1024w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-300x200.jpg 300w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-768x512.jpg 768w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-830x553.jpg 830w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-230x153.jpg 230w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-350x233.jpg 350w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920-480x320.jpg 480w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/lumber-84678_1920.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Der Gallenblasen-Meridian  <\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:44% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-1024x1024.png\" alt=\"\" class=\"wp-image-2105 size-full\" srcset=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-1024x1024.png 1024w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-300x300.png 300w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-150x150.png 150w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-768x768.png 768w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-1000x1000.png 1000w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-230x230.png 230w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-350x350.png 350w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase-480x480.png 480w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Gallenblase.png 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Er verl\u00e4uft vom \u00e4u\u00dferen Augenwinkel \u00fcber das Genick seitlich den Hals entlang. \u00dcber das Schultergelenk, weiter seitlich unregelm\u00e4\u00dfig den K\u00f6rper entlang, am H\u00fcfth\u00f6cker vorbei, um das H\u00fcftgelenk herum und das Bein au\u00dfen nach unten bis zum Huf.<\/p>\n<\/div><\/div>\n\n\n\n<p>Von vornherein, das Pferd besitzt KEINE Gallenblase, wohl aber einen Gallenblasen-Meridian. Der f\u00fcr die Verdauung n\u00f6tige Gallensaft wird in der Leber gebildet. In der TCM ist dieser Meridian zust\u00e4ndig f\u00fcr die Entscheidungsfindung und die Flexibilit\u00e4t der Sehnen. St\u00f6rungen in diesem Meridian \u00e4u\u00dfern sich in Sehnen-Problemen (h\u00e4ufiges stolpern oder Durchtrittigkeiten) oder durch Unentschlossenheit des Pferdes. <\/p>\n\n\n\n<p><strong>Der Leber-Meridian  <\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p>Er zieht von der Innenseite des Hufes kommend das Bein innen bis\nzur Flanke nach oben. Von dort aus verl\u00e4uft er bis zur 14. Rippe. \n<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-1024x1024.png\" alt=\"\" class=\"wp-image-2106 size-full\" srcset=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-1024x1024.png 1024w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-300x300.png 300w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-150x150.png 150w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-768x768.png 768w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-1000x1000.png 1000w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-230x230.png 230w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-350x350.png 350w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber-480x480.png 480w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/05\/GbLe-Leber.png 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>Die Leber ist zusammen mit der Milz ebenfalls f\u00fcr die Blutspeicherung zust\u00e4ndig, aber auch f\u00fcr wichtige Entgiftungsvorg\u00e4nge des K\u00f6rpers. Stoffwechselgifte werden hier ab- oder umgebaut, so dass diese unsch\u00e4dlich gemacht und ausgeschieden werden k\u00f6nnen. Eine St\u00f6rung dieser Prozesse \u00e4u\u00dfert sich vor allem in M\u00fcdigkeit und Leistungsabfall. Geht dies \u00fcber einen l\u00e4ngeren Zeitraum, k\u00f6nnen sich diese Gifte auch im Hufhorn ablagern. Dadurch k\u00f6nnen auch Hufprobleme eng mit der Leber zusammen h\u00e4ngen.  <\/p>\n\n\n\n<figure class=\"wp-block-image alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-26-at-11.45.49.jpeg\" alt=\"\" class=\"wp-image-715\" style=\"aspect-ratio:1.5024875621890548;width:394px;height:auto\" srcset=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-26-at-11.45.49.jpeg 640w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-26-at-11.45.49-300x200.jpeg 300w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-26-at-11.45.49-230x153.jpeg 230w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-26-at-11.45.49-350x233.jpeg 350w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-26-at-11.45.49-480x320.jpeg 480w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p>Der Leber-Meridian ist zust\u00e4ndig f\u00fcr die Augen, Sehnen und das Hufhorn des Pferdes. Probleme des Meridians \u00e4u\u00dfern sich  in spr\u00f6dem, rissigen Horn oder Augenproblemen. (Reitzungen der Bindeh\u00e4ute und Augenentz\u00fcndungen)  <\/p>\n\n\n\n<p>Jetzt wird es spannend. Ist dein Pferd ein Leber-Typ? Finden wir\nes heraus! \n<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ist dein Pferd dominant?<\/li>\n\n\n\n<li>Tritt es auch gerne mal aus? <\/li>\n\n\n\n<li>Hast es oft ein zusammen gekniffenes Maul? <\/li>\n\n\n\n<li>Ist es launisch?<\/li>\n\n\n\n<li>Legt es beim Putzen oder Satteln auch mal die Ohren an oder knappt?<\/li>\n\n\n\n<li>Hat es eine feste, fast harte Muskulatur oder ist oft verspannt?<\/li>\n\n\n\n<li>Ist es ehrgeizig und zeigt vollen K\u00f6rpereinsatz?<\/li>\n\n\n\n<li>Ist es in der Herde ranghoch?<\/li>\n\n\n\n<li>Hat es ein gutes Ged\u00e4chtnis?<\/li>\n\n\n\n<li>Dein Pferd ist mutig? <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195556_313.jpg\" alt=\"\" class=\"wp-image-638\" style=\"width:460px;height:306px\" srcset=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195556_313.jpg 612w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195556_313-300x200.jpg 300w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195556_313-230x153.jpg 230w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195556_313-350x233.jpg 350w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195556_313-480x320.jpg 480w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<p>Hast du die Fragen mit &#8222;Ja!&#8220; beantworten k\u00f6nnen? Dann hast du ein Pferd, das im Leber-Typ steht.  <\/p>\n\n\n\n<figure class=\"wp-block-image alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"918\" src=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195550_904.jpg\" alt=\"\" class=\"wp-image-637\" style=\"width:242px;height:362px\" srcset=\"https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195550_904.jpg 612w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195550_904-200x300.jpg 200w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195550_904-230x345.jpg 230w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195550_904-350x525.jpg 350w, https:\/\/nova-physiotherapie.de\/wp-content\/uploads\/2019\/04\/IMG_20190418_195550_904-480x720.jpg 480w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><\/figure>\n\n\n\n<p>Leber-Typen sind nichts f\u00fcr schwache Nerven oder Anf\u00e4nger. Man bekommt nichts geschenkt. Sie sind launisch und haben ihren eigenen Willen. Zum erreichen ihrer Ziele zeigen sie vollen K\u00f6rpereinsatz (ob gut oder schlecht) und teilen auch gerne mal aus. Leber-Typen sind mutig und wollen sich pr\u00e4sentieren, k\u00f6nnen aber auch schnell zornig werden. Sie haben ein au\u00dferordentlich gutes Ged\u00e4chtnis und vergessen fast nichts. So klappen auch Lektionen, die man seit langem nicht mehr abgefragt haben oft auf Anhieb. Beim putzen und satteln reagiert dieser Typ oft \u00fcberempfindlich oder &#8222;stutig&#8220;. Hat man den Leber-Typen allerdings auf seiner Seite wird er alles geben um euer Ziel zu erreichen.  <\/p>\n\n\n\n<p>Im Umgang mit dem Leber-Typ ist es wichtig ihn ausschweifend zu loben und ihn im Training mit einzubeziehen. Er braucht Abwechslung zwischen eingefordertem Arbeiten und freier Entscheidung um den Spa\u00df an der Sache nicht zu verlieren. Freilauf oder Freiarbeit vor dem Training geben ihm die M\u00f6glichkeit seine \u00fcbersch\u00fcssige Energie und Emotionen abzubauen.  \u00dcberforderung oder gar Zwang machen ihn zornig. Da kann er schon mal zum Rodeopferd wie aus den Filmen werden. Sein gutes Ged\u00e4chtnis merkt sich auch schlechte Erfahrungen, daher ist ein fairer und konsequenter Umgang besonders wichtig um ihm Halt zu geben und keine negativen Erfahrungen machen zu lassen. Er neigt zu Muskelverspannungen und Sehnenproblemen. <\/p>\n\n\n\n<p>Kommt er dir bekannt vor? Hast du ein Leber-Pferd?<br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/nova-physiotherapie.de\/index.php\/2019\/05\/05\/welches-element-gehoert-zu-meinem-pferd-wasser\/\">Nieren-Typ (Wasser) <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/nova-physiotherapie.de\/index.php\/2019\/05\/12\/welches-element-gehoert-zu-meinem-pferd-feuer\/\">Herz-Typ (Feuer) <\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/nova-physiotherapie.de\/index.php\/2019\/05\/19\/welches-element-gehoert-zu-meinem-pferd-erde\/\">Milz-Typ (Erde)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/nova-physiotherapie.de\/index.php\/2019\/05\/26\/welches-element-gehoert-zu-meinem-pferd-metall\/\">Lungen-Typ (Metall)<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>In der traditionellen chinesischen Medizin, kurz TCM k\u00f6nnen Pferde in f\u00fcnf unterschiedliche Typen eingeteilt werden. Diese entsprechen einem jeweiligen Organ und dessen Leitbahnen, sowie einem zugeh\u00f6rigen Element. Jeder Typ weist unterschiedliche k\u00f6rperliche und charakterliche Eigenschaften auf. Im Sinne der traditionellen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-621","post","type-post","status-publish","format-standard","hentry","category-welches-element-gehoert-zu-meinem-pferd"],"_links":{"self":[{"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/posts\/621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/comments?post=621"}],"version-history":[{"count":23,"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/posts\/621\/revisions"}],"predecessor-version":[{"id":2127,"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/posts\/621\/revisions\/2127"}],"wp:attachment":[{"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/media?parent=621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/categories?post=621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nova-physiotherapie.de\/index.php\/wp-json\/wp\/v2\/tags?post=621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}